{"id":7693,"date":"2024-02-16T14:31:18","date_gmt":"2024-02-16T14:31:18","guid":{"rendered":"https:\/\/hairtaminmorocco.com\/?post_type=product&#038;p=7693"},"modified":"2024-02-16T14:33:01","modified_gmt":"2024-02-16T14:33:01","slug":"mass-tech-elite-2-72-kg-muscletech","status":"publish","type":"product","link":"https:\/\/hairtaminmorocco.com\/en\/product\/mass-tech-elite-2-72-kg-muscletech\/","title":{"rendered":"Mass-Tech Elite 2.72 Kg &#8211; Muscletech"},"content":{"rendered":"<h2>Pr\u00e9sentation de produit<\/h2>\n<p>Muscletech MASS-TECH ELITE La nouvelle formule avanc\u00e9e Hard gainer, d\u00e9velopp\u00e9e pour ceux qui ont du mal \u00e0 prendre du volume, ceux qui sont en phase de croissance ou ceux qui veulent briser le plateau !! Les prot\u00e9ines contribuent au maintien et d\u00e9veloppement de la masse musculaire.<\/p>\n<p>Mass Tech Elite contient 10g de cr\u00e9atine monohydrate, ce qui aide \u00e0 augmenter la force et les performances lors d\u2019efforts courts ou intenses. La formule contient des acides amin\u00e9s essentiels (BCAA) et de la L-Glutamine, permettant une meilleure construction musculaire mais aussi un gain d\u2019\u00e9nergie et d\u2019endurance et une bonne r\u00e9cup\u00e9ration.<\/p>\n<p>La formule contient une enzyme Prohydrolase\u00ae pour une absorption optimale des ingr\u00e9dients du gainer.<\/p>\n<h2>Utilisation<\/h2>\n<p>3 prises par jours. M\u00e9langez 2 cuill\u00e8res de poudre avec 250 ml d&rsquo;eau ou de lait \u00e9cr\u00e9m\u00e9 le matin, entre le petit d\u00e9jeuner et le d\u00e9jeuner. 2 cuill\u00e8res apr\u00e8s l\u2019entrainement avec 250 ml d&rsquo;eau, une derni\u00e8re 2 cuill\u00e8res avant de dormir avec 250 ml du lait \u00e9cr\u00e9m\u00e9.<\/p>\n<h2>Information nutritionnelle<\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.prodietnutrition.ma\/img\/cms\/New_Masstech_elite_SF.png\" alt=\"\" width=\"472\" height=\"786\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Haute teneur en prot\u00e9ines (80g)<\/p>\n<p>&#8211; 1000 calories par portion<\/p>\n<p>&#8211; Faible teneur en sucres et mati\u00e8res grasses<\/p>\n<p>&#8211; Contient 10g de cr\u00e9atine + BCAA et acides amin\u00e9s<\/p>","protected":false},"featured_media":7696,"template":"","meta":{"inline_featured_image":false},"product_cat":[46],"product_tag":[],"class_list":["post-7693","product","type-product","status-publish","has-post-thumbnail","product_cat-mass-gainers","product_brand-muscletech","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/hairtaminmorocco.com\/en\/wp-json\/wp\/v2\/product\/7693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hairtaminmorocco.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hairtaminmorocco.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/hairtaminmorocco.com\/en\/wp-json\/wp\/v2\/product\/7693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hairtaminmorocco.com\/en\/wp-json\/wp\/v2\/media\/7696"}],"wp:attachment":[{"href":"https:\/\/hairtaminmorocco.com\/en\/wp-json\/wp\/v2\/media?parent=7693"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hairtaminmorocco.com\/en\/wp-json\/wp\/v2\/product_cat?post=7693"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hairtaminmorocco.com\/en\/wp-json\/wp\/v2\/product_tag?post=7693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}